{"id":4723,"date":"2025-04-24T23:21:22","date_gmt":"2025-04-24T23:21:22","guid":{"rendered":"https:\/\/www.greenlatinos.org\/?p=4723"},"modified":"2025-04-24T23:21:23","modified_gmt":"2025-04-24T23:21:23","slug":"la-orden-sobre-mineria-en-aguas-profundas-da-prioridad-a-las-corporaciones-sobre-las-personas","status":"publish","type":"post","link":"https:\/\/www.greenlatinos.org\/es\/la-orden-sobre-mineria-en-aguas-profundas-da-prioridad-a-las-corporaciones-sobre-las-personas\/","title":{"rendered":"La orden sobre miner\u00eda en aguas profundas da prioridad a las corporaciones sobre las personas"},"content":{"rendered":"<p class=\"has-text-align-center\"><em>Esta nueva pol\u00edtica destruir\u00e1 los fr\u00e1giles ecosistemas marinos de aquellos que se encuentran cerca de las costas.<\/em><\/p>\n\n\n\n<p><strong>WASHINGTON- <\/strong>Hoy, <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/04\/unleashing-americas-offshore-critical-minerals-and-resources\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">la Casa Blanca anunci\u00f3 la firma de una Orden Ejecutiva<\/a> destructiva y extractiva que tendr\u00e1 consecuencias devastadoras para los ecosistemas marinos y para quienes disfrutan de estos majestuosos santuarios oce\u00e1nicos.&nbsp;<\/p>\n\n\n\n<p><strong>Tras la firma de esta Orden Ejecutiva, Directore del Programa Water Equity &amp; Ocean de GreenLatinos, Dre. Val Z. Sch\u00fcll, emiti\u00f3 la siguiente declaraci\u00f3n:<\/strong><\/p>\n\n\n\n<p><em>\u201cLa Orden Ejecutiva de hoy de la Casa Blanca para impulsar la miner\u00eda en aguas profundas es una medida desastrosa que da\u00f1ar\u00e1 los ecosistemas marinos, los pescadores en peque\u00f1a escala y las comunidades costeras.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Esta nueva pol\u00edtica prioriza directamente el beneficio privado de las corporaciones ricas sobre las personas que viven en nuestras costas o sus alrededores. Contin\u00faa la agenda de esta Administraci\u00f3n de poner nuestros oc\u00e9anos en riesgo para obtener ganancias monetarias.&nbsp;<\/em><\/p>\n\n\n\n<p><em>GreenLatinos y nuestros miembros denunciamos esta terrible decisi\u00f3n y estamos trabajando con nuestras comunidades para luchar contra este orden. Continuaremos destacando la importancia de mantener a nuestra comunidad a salvo de los continuos ataques a nuestros oc\u00e9anos y ecosistemas de agua dulce\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">###<\/p>\n\n\n\n<p><strong>Acerca de GreenLatinos<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>GreenLatinos <strong>(NOTA: GreenLatinos es UNA PALABRA)<\/strong> es una comunidad activa de l\u00edderes latinos\/a\/e, envalentonados por el poder y la sabidur\u00eda de nuestra cultura, unidos para exigir equidad y desmantelar el racismo, con recursos para ganar nuestra justicia ambiental, batallas de conservaci\u00f3n, clim\u00e1ticas e impulsadas a asegurar nuestra Liberaci\u00f3n pol\u00edtica, econ\u00f3mica, cultural y ambiental.<\/p>","protected":false},"excerpt":{"rendered":"<p>Esta nueva pol\u00edtica destruir\u00e1 los fr\u00e1giles ecosistemas marinos de aquellos que se encuentran cerca de las costas. WASHINGTON - Hoy, la Casa Blanca anunci\u00f3 la firma de una Orden Ejecutiva destructiva y extractiva que tendr\u00e1 consecuencias devastadoras para los ecosistemas marinos y para quienes disfrutan de estos majestuosos santuarios oce\u00e1nicos.&nbsp; Tras la firma de esta [&hellip;]<\/p>\n","protected":false},"author":1527,"featured_media":4724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[75,103],"federal_programs":[],"state_region":[],"class_list":["post-4723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","tag-press-releases-spanish","tag-water-equity-and-ocean"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts\/4723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/users\/1527"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/comments?post=4723"}],"version-history":[{"count":0,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts\/4723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/media\/4724"}],"wp:attachment":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/media?parent=4723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/categories?post=4723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/tags?post=4723"},{"taxonomy":"federal_programs","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/federal_programs?post=4723"},{"taxonomy":"state_region","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/state_region?post=4723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}