{"id":4297,"date":"2025-02-04T20:13:35","date_gmt":"2025-02-04T20:13:35","guid":{"rendered":"https:\/\/www.greenlatinos.org\/?p=4297"},"modified":"2025-02-04T20:13:36","modified_gmt":"2025-02-04T20:13:36","slug":"business-owners-veterans-outdoor-recreationists-and-conservation-leaders-from-maine-to-oregon-speak-up-for-national-monuments-in-wake-of-stealthy-review","status":"publish","type":"post","link":"https:\/\/www.greenlatinos.org\/es\/business-owners-veterans-outdoor-recreationists-and-conservation-leaders-from-maine-to-oregon-speak-up-for-national-monuments-in-wake-of-stealthy-review\/","title":{"rendered":"Propietarios de empresas, veteranos, aficionados a las actividades al aire libre y l\u00edderes conservacionistas desde Maine hasta Oreg\u00f3n se pronuncian a favor de los monumentos nacionales tras una revisi\u00f3n furtiva"},"content":{"rendered":"<p class=\"wp-block-paragraph\">PARA PUBLICACI\u00d3N INMEDIATA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CONTACTO: Juan Roberto Madrid, Defensor de Pol\u00edticas Energ\u00e9ticas y de Transporte Limpio de Colorado, juanmadrid@greenlatinos.org<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Durango, Colorado) \u2013 En su primer d\u00eda en el cargo, el presidente Donald Trump dej\u00f3 en claro en m\u00faltiples \u00f3rdenes ejecutivas que su administraci\u00f3n priorizar\u00eda ofrecer nuestra agua, nuestra vida silvestre y nuestros modos de vida como sacrificios a las empresas contaminadoras como parte de su agenda contra las tierras p\u00fablicas. Hoy, su reci\u00e9n confirmado secretario del Interior, Doug Burgum, tom\u00f3 esa direcci\u00f3n al firmar una orden que ordena una revisi\u00f3n inicial extremadamente breve de 15 d\u00edas de todas las tierras retiradas del desarrollo minero y de los combustibles f\u00f3siles, incluidos cientos de nuestros monumentos nacionales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Orden Secretarial 3418 \u201cLiberando la energ\u00eda estadounidense\u201d ordena que el Departamento del Interior, que administra millones de acres de tierras p\u00fablicas, incluidos nuestros senderos y campamentos, finalice su revisi\u00f3n inicial de monumentos antes del 18 de febrero. Esta orden siniestramente sutil se alinea con las acciones de Trump durante su primer mandato, cuando lider\u00f3 la mayor reducci\u00f3n de las protecciones de tierras p\u00fablicas en la historia, recortando los monumentos nacionales Bears Ears y Grand-Staircase Escalante de Utah en un 85 y un 47 por ciento, respectivamente. Sin embargo, en este caso, la revisi\u00f3n incluye todos los monumentos del pa\u00eds bajo el Departamento del Interior que se crearon a trav\u00e9s de la Ley de Antig\u00fcedades. A diferencia de 2017, no se menciona un per\u00edodo de comentarios p\u00fablicos que lo acompa\u00f1e. Es importante destacar que la orden no hace referencia ni a los monumentos nacionales ni a la Ley de Antig\u00fcedades por su nombre, refiri\u00e9ndose a esta \u00faltima solo por su n\u00famero de c\u00f3digo estadounidense.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de un ataque furtivo y antipatri\u00f3tico que ataca los cimientos mismos de las queridas tierras p\u00fablicas del pa\u00eds, incluidos los parques y monumentos nacionales. Estos tesoros nacionales son ampliamente apreciados. Salvaguardan nuestra agua, impulsan la econom\u00eda de la recreaci\u00f3n al aire libre, protegen nuestros senderos y preservan un patrimonio nacional rico en cultura y belleza natural. Los ataques a la vida al aire libre, como esta orden del Secretario Burgum, amenazan la econom\u00eda de la recreaci\u00f3n de 1.640.000 millones de d\u00f3lares, poniendo en riesgo millones de puestos de trabajo, en particular en estados rurales como Dakota del Norte.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La orden no reconoce que la producci\u00f3n de petr\u00f3leo alcanz\u00f3 niveles r\u00e9cord durante la administraci\u00f3n Biden. No se trata de dominio energ\u00e9tico. Los pol\u00edticos de Washington y sus asesores multimillonarios tienen una agenda antipatri\u00f3tica contra las tierras p\u00fablicas que apunta a desmantelar nuestros monumentos nacionales para los contaminadores corporativos. Esta acci\u00f3n del Secretario Burgum es parte de un plan m\u00e1s amplio para vender nuestras tierras p\u00fablicas, patrimonio nacional y acceso al aire libre a los ricos y bien conectados que bloquear\u00e1 el acceso de los estadounidenses comunes para practicar senderismo, acampar, cazar y pescar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Corte Suprema ha confirmado la autoridad del Presidente para crear monumentos nacionales. Tanto presidentes dem\u00f3cratas como republicanos \u2013incluido Donald Trump\u2013 han utilizado esta ley para salvaguardar lugares vitales en beneficio del pueblo estadounidense. El presidente republicano Teddy Roosevelt promulg\u00f3 esta ley hace casi 120 a\u00f1os con este prop\u00f3sito.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos lugares preciados, que desempe\u00f1an un papel vital en la protecci\u00f3n del agua potable, el refugio de la vida silvestre y la garant\u00eda del acceso al aire libre, se establecieron con la intenci\u00f3n expresa de preservar el patrimonio cultural y ecol\u00f3gico de la naci\u00f3n para todos, honrando a las generaciones pasadas, presentes y futuras. Los monumentos nacionales que la administraci\u00f3n Trump est\u00e1 revisando cuentan con el apoyo de las comunidades y empresas locales que trabajaron durante a\u00f1os para garantizar su protecci\u00f3n. Estas acciones no son solo una afrenta a las tierras y aguas p\u00fablicas, sino que son ataques al liderazgo de las comunidades ind\u00edgenas y las naciones tribales que han trabajado durante a\u00f1os para proteger estos lugares.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agenda del presidente Trump no cuenta con el respaldo del p\u00fablico. Los monumentos y parques nacionales son extremadamente populares. El ochenta y cinco por ciento de los votantes del oeste cree que los presidentes estadounidenses deber\u00edan crear m\u00e1s de estos lugares. Los votantes de Utah, tanto republicanos como dem\u00f3cratas, apoyan abrumadoramente los monumentos nacionales de Bears Ears y Grand Staircase-Escalante, y m\u00e1s del 70 por ciento est\u00e1 a favor de mantenerlos como monumentos nacionales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando el presidente Trump intent\u00f3 por primera vez reducir el tama\u00f1o de los monumentos nacionales marinos Bears Ears, Grand Staircase-Escalante y Northeast Canyons and Seamounts en 2017, millones de estadounidenses se opusieron. Hoy, en respuesta a esta decisi\u00f3n de la Secretar\u00eda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La orden, un coro de empresarios, aficionados a las actividades al aire libre, l\u00edderes religiosos y conservacionistas de todo el pa\u00eds, desde Maine hasta Oreg\u00f3n, est\u00e1n alzando la voz en defensa de estos lugares. La orden de hoy plantea una amenaza a todas nuestras tierras p\u00fablicas, aguas y monumentos nacionales. Al hacerlo, erosiona el compromiso del pa\u00eds con la soberan\u00eda tribal, el acceso permanente a la naturaleza, la protecci\u00f3n del agua y la vida silvestre y el crecimiento de las econom\u00edas rurales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>APOYO A NUESTROS MONUMENTOS NACIONALES&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veteranos&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Janessa Goldbeck, veterana militar y directora ejecutiva de Vet Voice Foundation, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>La Ley de Antig\u00fcedades es una de las herramientas m\u00e1s importantes de Estados Unidos para preservar nuestra historia, cultura y patrimonio natural. Durante m\u00e1s de un siglo, los presidentes de ambos partidos han utilizado esta ley para proteger lugares emblem\u00e1ticos como el Gran Ca\u00f1\u00f3n y la Estatua de la Libertad, garantizando que estos tesoros sigan siendo accesibles para todos los estadounidenses.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Los monumentos nacionales fortalecen nuestras comunidades y estimulan las econom\u00edas locales. Estas designaciones crean puestos de trabajo, apoyan a las peque\u00f1as empresas y brindan oportunidades recreativas de bajo costo para familias, cazadores, pescadores y entusiastas de las actividades al aire libre. Para los veteranos y las familias militares, estas tierras ofrecen lugares para reconectarse y encontrar la paz.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Los esfuerzos por socavar la Ley de Antig\u00fcedades amenazan nuestra capacidad de preservar estos sitios cr\u00edticos e ignoran el amplio apoyo bipartidista a la protecci\u00f3n de las tierras p\u00fablicas de Estados Unidos. Como veterano, comprendo lo mucho que significan estos lugares para quienes han servido. Debemos mantenernos firmes en la tarea de garantizar que estas tierras est\u00e9n protegidas para que las generaciones futuras puedan disfrutarlas y beneficiarse de ellas\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juan Roberto Madrid, veterano de la Marina y defensor de pol\u00edticas de energ\u00eda y transporte limpio de Colorado, Green Latinos, dijo: <\/strong><em>\u201cComo veterano latino que sirvi\u00f3 durante 22 a\u00f1os y presenci\u00f3 m\u00faltiples despliegues de combate, incluida la Primera Guerra del Golfo, las guerras de Irak y Afganist\u00e1n, he experimentado de primera mano el profundo impacto que tiene la naturaleza en el bienestar f\u00edsico y mental. Despu\u00e9s de a\u00f1os de servicio, la tranquila soledad de un parque nacional, la inmensidad de un paisaje des\u00e9rtico como el Monumento Nacional Castner Range, el paisaje des\u00e9rtico de las altas llanuras del Monumento Nacional Bears Ears o la tranquilidad de un sendero costero como los del Monumento Nacional Cabrillo, me ofrecieron a m\u00ed y a otros veteranos un santuario para la curaci\u00f3n. Los desaf\u00edos que enfrentan los veteranos (TEPT, ansiedad, depresi\u00f3n) a menudo est\u00e1n profundamente entrelazados con el estr\u00e9s del combate y las dificultades de la reintegraci\u00f3n. El acceso a los espacios abiertos proporciona un salvavidas vital. Proteger y ampliar el acceso a nuestras tierras p\u00fablicas y monumentos nacionales no se trata solo de conservaci\u00f3n y preservaci\u00f3n de la belleza natural; se trata de invertir en la salud y el bienestar de nuestros veteranos. Estos espacios son recursos esenciales para la curaci\u00f3n, la recuperaci\u00f3n y un renovado sentido de prop\u00f3sito\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nancy Kramer, presidenta de la Fundaci\u00f3n 10th Mountain, dijo: \u201c<\/strong><em>El Monumento Nacional Camp Hale-Continental Divide, que abarca el \u00faltimo campo de entrenamiento de la Segunda Guerra Mundial totalmente abierto al p\u00fablico, fue creado expresamente para honrar a los veteranos y la enorme influencia positiva que tuvieron en nuestra naci\u00f3n. Cualquier alteraci\u00f3n en este lugar es una deshonra para esa historia militar, as\u00ed como una alteraci\u00f3n de la creciente industria de recreaci\u00f3n al aire libre de nuestro pa\u00eds, que constituye el 2,31 TP3T del PIB de EE. UU. y aporta m\u00e1s de 5 millones de empleos. En pocas palabras, atacar a Camp Hale revocando su designaci\u00f3n de monumento disminuir\u00eda la capacidad de nuestro pa\u00eds para trabajar hacia una econom\u00eda diversificada. La revocaci\u00f3n ser\u00eda enormemente antipatri\u00f3tica\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Negocios&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carrie Hamblen, senadora estatal y directora ejecutiva y presidenta de la C\u00e1mara de Comercio Verde de Las Cruces, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>El Monumento Nacional Organ Mountains-Desert Peaks de Nuevo M\u00e9xico es bueno para los negocios. Desde que se design\u00f3 como monumento nacional en 2014, ha generado un impacto econ\u00f3mico acumulado de m\u00e1s de 1.234 millones de d\u00f3lares, ha triplicado las visitas y ha respaldado 305 puestos de trabajo. Esa es una de las muchas razones por las que la ciudad de Las Cruces y el condado de Do\u00f1a Ana han apoyado tanto al monumento desde el primer d\u00eda. Cualquier ataque a este monumento y a otros en todo el pa\u00eds ignora a los gobiernos locales, las voces y las empresas locales y la comunidad que quiere que estos lugares est\u00e9n protegidos\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gail Fanjoy, presidenta de la C\u00e1mara de Comercio de Katahdin, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Como ciudadano de cuarta generaci\u00f3n de Millinocket, Maine, estoy profundamente comprometido con la revitalizaci\u00f3n de mi comunidad y otras comunidades de la regi\u00f3n de Katahdin. He servido en varios mandatos en el Concejo Municipal, un trabajo de servicio p\u00fablico que me permite presenciar de primera mano los beneficios que los monumentos nacionales aportan a nuestras comunidades rurales, tanto en Maine como en el pa\u00eds. Como director ejecutivo jubilado y l\u00edder c\u00edvico, ayud\u00e9 a liderar<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La manera de establecer el Monumento Nacional Bosques y Aguas de Katahdin. Este lugar ayuda a mantener la salud p\u00fablica y econ\u00f3mica de nuestras comunidades circundantes, atrayendo visitantes de todo el mundo y consagrando el acceso de los lugare\u00f1os a la naturaleza. Luch\u00e9 para establecer permanentemente Bosques y Aguas de Katahdin para m\u00ed, mi familia y mis vecinos. Cualquier precedente para abolir los monumentos nacionales ataca el coraz\u00f3n mismo de Millinocket y pueblos circundantes como este, cuyas&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLas empresas locales dependen del acceso permanente a estos paisajes extraordinarios\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nick Streit, propietario de una empresa y director de Amigos del Monumento Nacional del R\u00edo Grande del Norte, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>&quot;Me incorpor\u00e9 al negocio familiar a una edad temprana (mi padre escribi\u00f3 literalmente el libro sobre pesca con mosca en Nuevo M\u00e9xico) y he estado guiando a pescadores desde antes de tener la edad suficiente para llevarlos al r\u00edo. Hace veinte a\u00f1os, mi esposa y yo abrimos Taos Fly Shop, que creci\u00f3 desde sus humildes comienzos hasta convertirse en una de las principales tiendas de pesca con mosca del estado. Como fundador de una peque\u00f1a empresa, no puedo enfatizar lo suficiente el valor de las tierras p\u00fablicas protegidas de forma permanente, como el Monumento Nacional del R\u00edo Grande del Norte. Sin un acceso p\u00fablico protegido al r\u00edo, nuestro sustento, y de hecho, todo nuestro estilo de vida, estar\u00eda en peligro. Si se eliminan los monumentos nacionales, empresas como la m\u00eda podr\u00edan desaparecer y las econom\u00edas rurales que dependen de ellas sufrir\u00edan&quot;.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u00edderes espirituales&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reverendo Andrew Black, deportista y ministro presbiteriano, Primera Iglesia Presbiteriana de Santa Fe, <\/strong><em>\u201cComo deportista y padre, el Monumento Nacional del R\u00edo Grande del Norte es el lugar donde mi hija y yo disfrutamos de pescar, hacer caminatas y observar la incre\u00edble vida silvestre. Este monumento surgi\u00f3 y fue designado despu\u00e9s de a\u00f1os de apoyo y colaboraci\u00f3n comunitaria entre cazadores, pescadores, titulares de permisos para ganado, veteranos, funcionarios electos locales, due\u00f1os de negocios y organizaciones de vida silvestre. Como alguien que aprecia profundamente el rico patrimonio deportivo de los Estados Unidos, proteger los monumentos nacionales tiene que ver tanto con proteger el h\u00e1bitat cr\u00edtico para la vida silvestre, los sitios culturales, hist\u00f3ricos y sagrados como con proteger una forma de vida que podemos transmitir a las generaciones futuras\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Joseph Brophy Toledo, miembro del Pueblo Jemez y asesor espiritual tribal de EarthKeepers 360, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Los monumentos nacionales pueden ayudar a proteger nuestra cultura y nuestras tierras sagradas. Es importante que sigamos preservando el h\u00e1bitat de la vida silvestre protegido por nuestros monumentos nacionales y que seamos firmes en la defensa de los animales de cuatro patas, con aletas, alados y microinvertebrados\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deportistas&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David Lien, miembro de la junta directiva de Colorado Backcountry Hunters and Anglers, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>\u201cMe cri\u00e9 en Grand Rapids, Minnesota, y empec\u00e9 a cazar urogallos a los 11 a\u00f1os. A los 13 mat\u00e9 mi primer ciervo con un rifle Ruger .44 Magnum que me hered\u00f3 mi abuelo. Vengo de una familia multigeneracional de cazadores y veteranos militares y, como tal, comprendo el inmenso e incomparable valor de las tierras p\u00fablicas protegidas. Afortunadamente, Colorado es rico en lugares as\u00ed, desde el Monumento Nacional de Colorado en la ladera occidental hasta el Monumento Nacional Camp Hale-Continental Divide enclavado en las altas Monta\u00f1as Rocosas. Adem\u00e1s de proteger el h\u00e1bitat de las aves y la caza mayor, estos lugares garantizan que historias como las de mi familia se sigan contando durante generaciones. Un ataque a un monumento es un ataque a todos. Reducir el valor de cualquiera de estos lugares habla de un desprecio fundamental por los cazadores, pescadores y veteranos militares de este gran pa\u00eds\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mark Mattaini, miembro de la junta directiva de New Mexico Backcountry Hunters and Anglers, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Desde mi hogar en Paguate Village, Laguna Pueblo, en Nuevo M\u00e9xico, estoy rodeado de las impresionantes tierras ancestrales de los pueblos ind\u00edgenas. Desde las tierras altas del monte Taylor (mi sitio de caza m\u00e1s com\u00fan) hasta la diversidad volc\u00e1nica del Monumento Nacional El Malpa\u00eds, puedo visitar y explorar tierras p\u00fablicas protegidas en todas las direcciones. Pescador de nacimiento y todav\u00eda activo, tambi\u00e9n tengo grandes oportunidades de cazar aves de las tierras altas, aves acu\u00e1ticas y pavos salvajes, as\u00ed como ocasionalmente animales grandes. Experiencias de caza y pesca como las que tanto valoro solo son posibles en paisajes profundamente interconectados. Nuevo M\u00e9xico, desde el Monumento Nacional R\u00edo Grande del Norte en el norte hasta el Monumento Nacional Organ Mountains-Desert Peaks en el sur, es particularmente rico para los deportistas. Los monumentos nacionales, como los que se encuentran en todo Nuevo M\u00e9xico, desempe\u00f1an un papel esencial en la protecci\u00f3n de los corredores de vida silvestre, consagrando las formas de vida tradicionales y las oportunidades de caza. Atacar cualquier monumento amenaza todo el sistema de tierras y h\u00e1bitats interconectados\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dean Finnerty, miembro del personal de Trout Unlimited, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Durante m\u00e1s de 20 a\u00f1os, equilibr\u00e9 mi trabajo como gu\u00eda de pesca y caza con mi trabajo como agente de la ley. He capturado pr\u00e1cticamente todo tipo de peces en todos los arroyos de Oreg\u00f3n en los que vale la pena pescar, incluidas las aguas claras y fr\u00edas del incomparable Monumento Nacional Cascade-Siskiyou. Sin lugares protegidos de forma permanente como este monumento, la salud p\u00fablica y econ\u00f3mica de nuestras comunidades se ver\u00eda afectada.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLos l\u00edmites est\u00e1n destinados a durar a perpetuidad, por lo que yo, mi familia, mis vecinos y todos los que visitan este lugar podemos depender del h\u00e1bitat y refugio que ofrece\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Russel Kuhlman, director ejecutivo de la Federaci\u00f3n de Vida Silvestre de Nevada, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Cuando Theodore Roosevelt utiliz\u00f3 por primera vez la Ley de Antig\u00fcedades en 1906, sab\u00eda que las amenazas a las tierras p\u00fablicas avanzaban m\u00e1s r\u00e1pido que el Congreso. Cada monumento nacional designado en Nevada se hizo reuniendo a todas las partes interesadas y con fuertes campa\u00f1as de base lideradas por la comunidad local. Confiar en que el Congreso avance m\u00e1s r\u00e1pido que las amenazas que los habitantes de Nevada ven en las tierras p\u00fablicas no es el camino para garantizar que las generaciones futuras disfruten de nuestros recursos naturales y culturales. Es por eso que<\/em><em> 85 por ciento<\/em><em> \u201cEl 80% de los votantes occidentales apoya la creaci\u00f3n de nuevos parques nacionales, monumentos nacionales, refugios de vida silvestre y \u00e1reas tribales protegidas para proteger sitios hist\u00f3ricos o \u00e1reas de recreaci\u00f3n al aire libre\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jesse Deubel, director ejecutivo de la Federaci\u00f3n de Vida Silvestre de Nuevo M\u00e9xico, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>La New Mexico Wildlife Federation ha defendido a los cazadores y pescadores desde 1914. Como la organizaci\u00f3n de defensa deportiva m\u00e1s grande y antigua de nuestro estado, sabemos que la mayor amenaza para el futuro de la caza es la p\u00e9rdida de acceso al h\u00e1bitat salvaje que sustenta a poblaciones robustas de vida silvestre. Las designaciones de monumentos nacionales han demostrado ser una herramienta excepcional para proteger estos h\u00e1bitats a escala del paisaje en beneficio de los cazadores y otros entusiastas de la recreaci\u00f3n al aire libre que dependen de las tierras p\u00fablicas. Algunas de las oportunidades de caza m\u00e1s codiciadas en Nuevo M\u00e9xico existen gracias a nuestros monumentos nacionales. Los monumentos son verdaderamente para todas las personas. La idea de reducirlos o eliminarlos es un enorme perjuicio para el pueblo estadounidense y una amenaza significativa para el futuro de la caza\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alex Trimble Young, miembro de la junta directiva del cap\u00edtulo de Arizona de Backcountry Hunters and Anglers y ganador del premio Aldo Leopold 2024 de la Federaci\u00f3n de Vida Silvestre de Arizona por la defensa ciudadana, dijo:<\/strong><em>\u201c<\/em><em>En una \u00e9poca en la que parece que la polarizaci\u00f3n pol\u00edtica en Estados Unidos se intensifica cada vez m\u00e1s, las actitudes de los estadounidenses hacia las tierras p\u00fablicas siguen siendo un tema en el que todav\u00eda vemos un consenso abrumador y bipartidista de los votantes. Los estadounidenses creen en la necesidad de una protecci\u00f3n s\u00f3lida de nuestras tierras p\u00fablicas, punto. La reciente designaci\u00f3n de los monumentos nacionales de Chuckwalla y S\u00e1tt\u00edtla Highlands nos mostr\u00f3 esta poderosa coalici\u00f3n en acci\u00f3n, que re\u00fane a nuestras naciones ind\u00edgenas, ambientalistas y aficionados a las actividades al aire libre, desde excursionistas hasta cazadores, para brindar protecciones muy necesarias y ampliar el acceso a la ecolog\u00eda irremplazable y los sitios culturales antiguos de estos lugares notables.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Lamentablemente, un grupo cada vez m\u00e1s poderoso de pol\u00edticos de Washington que votan para servir a las cuentas bancarias de sus campa\u00f1as y no a los intereses de sus votantes est\u00e1 amenazando no s\u00f3lo estos monumentos, sino la propia legislaci\u00f3n -la Ley de Antig\u00fcedades, promulgada por Theodore Roosevelt- que hace posible la protecci\u00f3n futura de monumentos similares. Es hora de que los estadounidenses comunes de todos los tipos que aman nuestros lugares salvajes se pongan de pie y digan no a los pol\u00edticos codiciosos y a las corporaciones.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>intereses que impulsan la agenda de transferencia de tierras\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u00edderes de organizaciones y defensores locales&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tim Peterson, director de paisajes culturales del Grand Canyon Trust, dijo: <\/strong><em>\u201cLa Orden Secretarial del 3 de febrero para realizar una revisi\u00f3n discreta de las designaciones de monumentos nacionales es profundamente impopular en Utah, donde <\/em><em>casi dos tercios de<\/em><em> <\/em><em>Los votantes de Utah encuestados recientemente<\/em><em> <\/em><em>est\u00e1n a favor de mantener sus monumentos nacionales tal como est\u00e1n. 89% de esos votantes de Utah tambi\u00e9n dijeron&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLas tribus deber\u00edan tener voz y voto sobre c\u00f3mo se gestionan sus tierras ancestrales, que ahora se denominan tierras p\u00fablicas. La administraci\u00f3n entrante deber\u00eda respetar a las tribus manteniendo vigente el hist\u00f3rico acuerdo de gesti\u00f3n colaborativa y dejando intacto el Monumento Nacional Bears Ears y todos nuestros monumentos nacionales\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Kim Garrison Means, Amigos de Avi Kwa Ame, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Crec\u00ed dentro de los l\u00edmites de lo que es ahora <\/em><em>Avi Kwa Ame<\/em><em> <\/em><em>Monumento Nacional. Mis abuelos se mudaron aqu\u00ed, a un terreno de 60 acres en las afueras de Searchlight, Nevada, en la d\u00e9cada de 1960.<\/em><em> <\/em><em>Mi abuelo me ense\u00f1\u00f3 los nombres de la incre\u00edble variedad de plantas, animales, rocas y estrellas, un conocimiento que me fue muy \u00fatil.<\/em><em> <\/em><em>Me lo inculcaron como parte de mi experiencia del mundo. Tenemos todo tipo de vecinos y aprendimos a tratarnos entre nosotros.<\/em><em> <\/em><em>Otro con respeto. Este monumento nacional existe hoy, en parte, gracias al compromiso de mi peque\u00f1a ciudad con este<\/em><em> pag<\/em><em>Principio. Decidimos buscar el estatus de monumento para proteger el paisaje que apreciamos, como una decisi\u00f3n comunitaria.<\/em><em> <\/em><em>No fue un tema pol\u00edtico. Se trat\u00f3 de llegar a TODOS en nuestra comunidad. Nos reunimos durante a\u00f1os para debatir<\/em><em> <\/em><em>y reuniones p\u00fablicas en Searchlight, y tuvimos muchas m\u00e1s con nuestros vecinos rurales, tribales y urbanos. Avi Kwa Ame<\/em><em> <\/em><em>El Monumento Nacional es algo que nuestra comunidad se enorgullece de haber logrado juntos, y cualquier revocaci\u00f3n de estos<\/em><em> <\/em><em>Establecer l\u00edmites ahora ser\u00eda una afrenta directa a esas conversaciones de sala de estar y a nuestra toma de decisiones local.<\/em><em> <\/em><em>autonom\u00eda.&quot;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patrick Nolan, director ejecutivo de Amigos de R\u00edo Grande del Norte, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>El Monumento Nacional Organ Mountains-Desert Peaks es un excelente ejemplo del impacto abrumadoramente positivo que las tierras protegidas pueden tener en una comunidad. Desde los impactos econ\u00f3micos solamente, $25 millones anuales, hasta las mayores oportunidades de recreaci\u00f3n al aire libre que cre\u00f3 la protecci\u00f3n, proteger las tierras p\u00fablicas siempre es una buena idea. Tambi\u00e9n hemos visto c\u00f3mo este monumento nos ha ayudado a desarrollar y fomentar una comunidad m\u00e1s fuerte que se une en torno al amor compartido por nuestras monta\u00f1as y tierras circundantes. Es a trav\u00e9s de la protecci\u00f3n que podemos honrar la historia de esta tierra y preservar ese legado para las generaciones futuras. Nuestro monumento ha transformado nuestra comunidad y seguir\u00e1 haci\u00e9ndolo en el futuro\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Daniel Collay, director ejecutivo de Amigos del Monumento Nacional Cascade-Siskiyou, dijo: <\/strong><strong><em>\u201c<\/em><\/strong><em>Crec\u00ed en Oreg\u00f3n y he dedicado mi vida a trabajar al aire libre. Mi pasi\u00f3n por las plantas, la vida silvestre y la conservaci\u00f3n impulsa todo lo que hago, y estoy agradecido de poder compartirla con visitantes de todo el mundo, as\u00ed como con los lugare\u00f1os y personas de todas las edades, incluidos los j\u00f3venes estudiantes, que vienen a conocer el Monumento Nacional Cascade-Siskiyou de 114.000 acres. Juntos, creemos en la protecci\u00f3n de este monumento para que las generaciones futuras puedan seguir cuid\u00e1ndolo y protegi\u00e9ndolo.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Cascade-Siskiyou, que se extiende a lo largo de la frontera entre Oreg\u00f3n y California, es una joya ecol\u00f3gica que alberga una extraordinaria diversidad de plantas y animales. Su rico mosaico de bosques, praderas, prados h\u00famedos y desierto interior lo convierte en un refugio incomparable para la vida silvestre. En cualquier caminata, es posible que vea una de las m\u00e1s de 300 especies de aves, mam\u00edferos, reptiles y anfibios que dependen de la integridad ecol\u00f3gica de este monumento para prosperar.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carmichael Dom\u00ednguez, ex concejal de la ciudad de Santa Fe y organizador de la comunidad hispana, EarthKeepers 360, \u201c<\/strong><em>Como ex concejal de la ciudad de Santa Fe, represent\u00e9 al distrito m\u00e1s joven, m\u00e1s pobre y el \u00fanico con mayor\u00eda\/minor\u00eda de la ciudad. Comprend\u00ed el papel vital que desempe\u00f1an las tierras p\u00fablicas en la calidad de vida de estas poblaciones. Los monumentos nacionales son cruciales, ya que reflejan los valores cambiantes de la sociedad estadounidense y brindan un mecanismo para preservar las tierras p\u00fablicas para las poblaciones vulnerables. La Ley de Antig\u00fcedades de 1906, que permite al presidente designar monumentos nacionales, ha sido una piedra angular de la preservaci\u00f3n federal y puede ser una herramienta importante para elevar la calidad de vida de las personas en general\u201d.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">###<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de GreenLatinos \u2013\n\nGreenLatinos (NOTA: GreenLatinos es UNA PALABRA) convoca a una comunidad activa de l\u00edderes ambientales, de conservaci\u00f3n y de justicia clim\u00e1tica, arraigada en el poder y la sabidur\u00eda de nuestra cultura, unida para impulsar nuestras prioridades y motivada a asegurar nuestra liberaci\u00f3n pol\u00edtica, econ\u00f3mica, cultural y ambiental.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GreenLatinos&nbsp;<strong>(NOTA: GreenLatinos es UNA PALABRA)<\/strong>&nbsp;es una comunidad activa de l\u00edderes latinos, envalentonados por el poder y la sabidur\u00eda de nuestra cultura, unidos para exigir equidad y desmantelar el racismo, con recursos para ganar nuestras batallas ambientales, de conservaci\u00f3n y de justicia clim\u00e1tica, y motivados para asegurar nuestras pol\u00edticas, Liberaci\u00f3n econ\u00f3mica, cultural y ambiental.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">GreenLatinos&nbsp;<strong>(NOTA: GreenLatinos es UNA PALABRA)<\/strong>&nbsp;es una comunidad activa de l\u00edderes latinos\/a\/e, envalentonados por el poder y la sabidur\u00eda de nuestra cultura, unidos para exigir equidad y desmantelar el racismo, con recursos para ganar nuestra justicia ambiental, batallas de conservaci\u00f3n, clim\u00e1ticas e impulsadas a asegurar nuestra Liberaci\u00f3n pol\u00edtica, econ\u00f3mica, cultural y ambiental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>FOR IMMEDIATE RELEASE CONTACT: Juan Roberto Madrid, Colorado Clean Transportation &amp; Energy Policy Advocate, juanmadrid@greenlatinos.org (Durango, CO) \u2013 On his first day in office, President Donald Trump made clear in multiple Executive Orders that his Administration would prioritize offering up our water, our wildlife, and our ways of life as sacrifices to corporate polluters as [&hellip;]<\/p>\n","protected":false},"author":149,"featured_media":2918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[74],"federal_programs":[],"state_region":[],"class_list":["post-4297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","tag-press-releases"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts\/4297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/comments?post=4297"}],"version-history":[{"count":0,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts\/4297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/media\/2918"}],"wp:attachment":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/media?parent=4297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/categories?post=4297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/tags?post=4297"},{"taxonomy":"federal_programs","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/federal_programs?post=4297"},{"taxonomy":"state_region","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/state_region?post=4297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}