{"id":3424,"date":"2024-09-28T00:24:40","date_gmt":"2024-09-28T00:24:40","guid":{"rendered":"https:\/\/www.greenlatinos.org\/?p=3424"},"modified":"2024-09-28T00:24:41","modified_gmt":"2024-09-28T00:24:41","slug":"were-taking-a-bite-out-of-ev-truck-myths-during-climate-week","status":"publish","type":"post","link":"https:\/\/www.greenlatinos.org\/es\/were-taking-a-bite-out-of-ev-truck-myths-during-climate-week\/","title":{"rendered":"Durante la Semana del Clima, desmitificamos los camiones el\u00e9ctricos"},"content":{"rendered":"<p>Es la Semana del Clima en Nueva York, y afuera de mi ventana, el tr\u00e1fico en la Interestatal 278 (conocida aqu\u00ed como BQE, o Brooklyn-Queens Expressway)... <a href=\"https:\/\/nytrucks.org\/tany-news\/blog\/83-bqe\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">17.000 camiones<\/a> diariamente arrojan humos t\u00f3xicos las 24 horas del d\u00eda, siete d\u00edas a la semana, trayendo mercanc\u00edas a la ciudad y al resto del estado.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pero se vislumbra un cambio en el horizonte de la contaminaci\u00f3n. Esta primavera, la Agencia de Protecci\u00f3n Ambiental aprob\u00f3 normas de contaminaci\u00f3n m\u00e1s estrictas para los camiones pesados, y los estados de todo el pa\u00eds est\u00e1n adoptando normas m\u00e1s estrictas que las federales para camiones limpios a fin de abordar sus problemas de calidad del aire.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC10516300\/#:~:text=We%20show%20that%20areas%20with,and%20Hispanic%20or%20Latino%20populations.\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Exposici\u00f3n<\/a> La respuesta a estos problemas de contaminaci\u00f3n es m\u00e1s evidente en las comunidades negras, latinas y de bajos ingresos. Al haber sido marginadas por pol\u00edticas de vivienda perjudiciales durante generaciones, las comunidades de color pueden encontrarse en el centro de \u201c<a href=\"https:\/\/www.catf.us\/deathsbydiesel\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">zonas de muerte del di\u00e9sel<\/a>\u201d cerca de almacenes, puertos, centros de carga y centros de tr\u00e1nsito. Esta exposici\u00f3n desproporcionada a la contaminaci\u00f3n del aire es uno de los ejemplos m\u00e1s claros de racismo ambiental, que aumenta el riesgo de defectos de nacimiento, enfermedades pulmonares, asma y c\u00e1ncer. Lamentablemente, <a href=\"https:\/\/minorityhealth.hhs.gov\/asthma-and-hispanic-americans#:~:text=Hispanics%20are%20twice%20as%20likely,compared%20to%20non%2DHispanic%20whites.\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Ni\u00f1os latinos\/as<\/a> visitan la sala de emergencias debido al asma a una tasa dos veces mayor que los ni\u00f1os blancos no hispanos y tienen un 40% m\u00e1s de probabilidades de morir de asma.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A pesar de que las normas que reducen la contaminaci\u00f3n nociva en estas comunidades son beneficiosas para todos, los fabricantes de camiones, las flotas de camiones y la industria petrolera han estado trabajando para debilitar, retrasar o hacer retroceder estas normas. Mientras testifican, litigan y difunden mitos en los medios de comunicaci\u00f3n en cada oportunidad que tienen para decir que no pueden cumplir con normas m\u00e1s estrictas, <a href=\"https:\/\/subscriber.politicopro.com\/article\/eenews\/2023\/09\/12\/truck-makers-oppose-epa-tailpipe-plan-despite-public-pledges-00115095\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Lo hacen parecer p\u00fablicamente<\/a> como si los apoyaran. Los fabricantes de camiones est\u00e1n incluso <a href=\"https:\/\/www.volvotrucks.com\/en-en\/trucks\/electric.html\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Despliegue de camiones el\u00e9ctricos<\/a> a <a href=\"https:\/\/www.iea.org\/data-and-statistics\/charts\/electric-truck-registrations-and-sales-share-by-region-2015-2023\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">satisfacer la creciente demanda<\/a> para tecnolog\u00edas libres de contaminaci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para refutar directamente los mitos generalizados y da\u00f1inos sobre los camiones el\u00e9ctricos difundidos por la industria, estamos organizando un evento especial durante la Semana del Clima para ofrecer una <a href=\"https:\/\/www.greenlatinos.org\/es\/events\/ev-truck-myths\/\">Hoja informativa sobre el \u201cs\u00e1ndwich de la verdad\u201d<\/a>.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Un \u201cs\u00e1ndwich de verdad\u201d es una herramienta educativa visual que aborda la desinformaci\u00f3n presentando datos digeribles sobre un tema (porci\u00f3n superior), abordando la desinformaci\u00f3n (carne o prote\u00edna) y luego resumiendo la realidad (porci\u00f3n inferior). Con este formato, arrojaremos luz sobre la preparaci\u00f3n de los camiones el\u00e9ctricos, los beneficios para la salud de eliminar los gases de escape de los di\u00e9sel, los ahorros que los camiones libres de contaminaci\u00f3n pueden generar para las flotas y la sociedad, y el lanzamiento estrat\u00e9gico de la infraestructura de carga.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por ejemplo, aqu\u00ed est\u00e1 la \u201cprote\u00edna\u201d en nuestra \u201cBaguette Breathe Easy\u201d:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A nivel nacional, la contaminaci\u00f3n del aire da\u00f1ina en los barrios latinos es fuertemente... <a href=\"https:\/\/www.lung.org\/blog\/air-pollution-latino-community\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Vinculado a la industria del transporte<\/a>.<\/li>\n\n\n\n<li>La quema de combustibles produce holl\u00edn, una contaminaci\u00f3n por part\u00edculas finas (PM2,5) <a href=\"https:\/\/www.epa.gov\/pm-pollution\/health-and-environmental-effects-particulate-matter-pm\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Se aloja profundamente en los pulmones y acorta las vidas.<\/a>.<\/li>\n\n\n\n<li>Casi 90,7 millones de personas viven en condados con calificaciones reprobatorias en <a href=\"https:\/\/www.lung.org\/research\/sota\/key-findings\/year-round-particle-pollution\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">contaminaci\u00f3n por part\u00edculas<\/a>.<\/li>\n\n\n\n<li>Al pasar a camiones el\u00e9ctricos y energ\u00eda limpia, los condados de EE. UU. con importantes rutas de transporte por carretera podr\u00edan <a href=\"https:\/\/www.lung.org\/getmedia\/e1ff935b-a935-4f49-91e5-151f1e643124\/zero-emission-truck-report.pdf\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Prevenir al menos 66.800 muertes prematuras<\/a> para el a\u00f1o 2050.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"789\" height=\"1024\" src=\"https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-789x1024.png\" alt=\"\" class=\"wp-image-3425\" srcset=\"https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-789x1024.png 789w, https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-231x300.png 231w, https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-768x997.png 768w, https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-1183x1536.png 1183w, https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-1577x2048.png 1577w, https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3-9x12.png 9w, https:\/\/www.greenlatinos.org\/wp-content\/uploads\/2024\/09\/Climate-Week-Truth-Sandwich-Fact-Sheet-Digital_Part3.png 2550w\" sizes=\"(max-width: 789px) 100vw, 789px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"c2\"><style>\n        .custom-button {<br \/>            background-color: #4A7729; \/* Green background *\/<br \/>            color: white; \/* White text *\/<br \/>            font-family: 'Montserrat', sans-serif; \/* Custom font *\/<br \/>            font-size: 30px; \/* Font size *\/<br \/>            padding: 10px 20px; \/* Padding *\/<br \/>            border: none; \/* No border *\/<br \/>            border-radius: 5px; \/* Rounded corners *\/<br \/>            cursor: pointer; \/* Pointer cursor on hover *\/<br \/>            text-decoration: none; \/* Remove underline *\/<br \/>            display: inline-block; \/* Allow padding and margins *\/<br \/>            transition: background-color 0.3s; \/* Smooth background color transition *\/<br \/>        }<\/p>\n<p>        .custom-button:hover {<br \/>            background-color: #45a049; \/* Darker green on hover *\/<br \/>        }<br \/>    <\/style><\/p>\n<a href=\"https:\/\/drive.google.com\/file\/d\/1cNKPX3wEPOJiDCue_gXUTumL1gEdYous\/view?usp=drive_link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n<button class=\"custom-button\">DESCARGAR LA HOJA INFORMATIVA<\/button>\n<\/a>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Los malos actores de la industria est\u00e1n haciendo todo lo posible para difundir informaci\u00f3n err\u00f3nea sobre la electrificaci\u00f3n de los camiones, mientras que la contaminaci\u00f3n por di\u00e9sel sigue acortando las vidas de las comunidades de color. Estamos entusiasmados por ofrecer algo de verdad.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00a1Buen provecho!<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>It\u2019s Climate Week in New York, and outside my window, traffic on Interstate 278 (known here as the BQE, or Brooklyn-Queens Expressway) about 17,000 trucks daily spew toxic fumes 24 hours a day, seven days a week, bringing goods into the city and the rest of state.&nbsp; But there is change on the smoggy horizon. [&hellip;]<\/p>\n","protected":false},"author":154,"featured_media":3334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[],"federal_programs":[],"state_region":[],"class_list":["post-3424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts\/3424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/users\/154"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/comments?post=3424"}],"version-history":[{"count":0,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/posts\/3424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/media\/3334"}],"wp:attachment":[{"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/media?parent=3424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/categories?post=3424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/tags?post=3424"},{"taxonomy":"federal_programs","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/federal_programs?post=3424"},{"taxonomy":"state_region","embeddable":true,"href":"https:\/\/www.greenlatinos.org\/es\/wp-json\/wp\/v2\/state_region?post=3424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}